{"id":395,"date":"2009-10-31T08:11:22","date_gmt":"2009-10-31T08:11:22","guid":{"rendered":"https:\/\/www.palandun.de\/?p=395"},"modified":"2020-02-29T08:11:49","modified_gmt":"2020-02-29T08:11:49","slug":"wie-so-eine-zeitung-entsteht","status":"publish","type":"post","link":"https:\/\/www.palandun.de\/index.php\/2009\/10\/31\/wie-so-eine-zeitung-entsteht\/","title":{"rendered":"Wie so eine Zeitung entsteht"},"content":{"rendered":"\n<p>Mythen und Sagen umranken die BILD-Zeitung. Ger\u00fcchteweise soll die \nZeitung 1952 von einem Herrn Springer in die Welt geschmissen worden \nsein. Das sind aber wirklich nur Ger\u00fcchte. Unsere Nachforschungen \nergaben ein ganz anderes Bild.<\/p>\n\n\n\n<p>In den Nachkriegsjahren steckte der\n Hamburger Fischmarkt in einer Krise. Es begab sich im Jahre 1951, dass \ndurch einen dummen Zufall ein Hamburger Fischer eine Verbesserung des \nEinpackpapiers gelang. Er holte das Papier gerade aus der Druckerei \nseines Cousins ab, als er bemerkte, dass aus der Druckerpresse \nDruckerschw\u00e4rze auf sein Verpackungsmaterial gespr\u00fcht worden war. Der \nFischer, der nur als Bargen-Rolf bekannt war, lie\u00df sich davon nicht \nirritieren. Er bekam das Papier kostenlos, also nahm er auch das leicht \nbeschmutzte. Auch die Kundschaft konnte er leicht beruhigen mit den \nWorten: \u201eVerpackung kost nix.\u201c<\/p>\n\n\n\n<p>Zu seiner Verwunderung stieg in den\n n\u00e4chsten Tagen sein Fischverkauf so an, dass er schon nach 2 Wochen \neinen Helfer anstellen musste. Nachfragen ergaben, dass seine Fische \neinfach besser schmeckten.<\/p>\n\n\n\n<p>An dieser Stelle h\u00e4tte die Geschichte \neine ganz andere Wendung nehmen k\u00f6nnen. Ein namentlich unbekannter \nRivale hatte die Geschehnisse am Nebenverkaufstisch beobachtet und \nbestellte als Verpackung Papier, dass gleich in Druckerschw\u00e4rze \neingelegt worden war. Es stellte sich allerdings heraus, dass das dann \ndoch ein bisschen viel war: das Zeug schmeckte nicht, er ging pleite.<\/p>\n\n\n\n<p>Bargen-Rolf\n hingegen begann zu experimentieren, als die urspr\u00fcngliche Charge \naufgebraucht war. Schon bald stellte sich heraus, dass der Druck von \nBuchstaben auf dem Papier f\u00fcr den optimalen Druckerschw\u00e4rze-Grad sorgte.\n Bargen-Rolf kaufte eine Ladung von zehn Schimpansen und setzte sie an \nSchreibmaschinen. T\u00e4glich 8 Stunden mussten Sie einfach nur Buchstaben \naufs Papier bringen.<\/p>\n\n\n\n<p>Sein Verkauf stieg durch diesen neuerlichen Coup ins Unermessliche.<\/p>\n\n\n\n<p>Zu\n seinem Erstaunen bemerkte er bald, dass einige Kunden das ganze dann \nsogar lasen. Sie waren sogar sehr angetan. Er dachte sich nicht viel \ndabei. Nach einiger Zeit kamen sogar Leute, die extra wegen der \nVerpackung bei ihm kauften. \u201eSoll ich den Fisch einpacken?\u201c \u201eNee, lassen\n Se mal. Geben Sie mir einfach die Verpackung, den Fisch k\u00f6nnen Sie \nbehalten.\u201c<\/p>\n\n\n\n<p>Bargen-Rolf begann, einfach nur noch die Verpackung zu \nverkaufen. Er suchte sich einen Verleger, den Herrn Springer, um einen \nh\u00f6heren Verbreitungsgrad zu erreichen.<\/p>\n\n\n\n<p>Und so begann der Siegeszug der Bild-Zeitung.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mythen und Sagen umranken die BILD-Zeitung. Ger\u00fcchteweise soll die Zeitung 1952 von einem Herrn Springer in die Welt geschmissen worden sein. Das sind aber wirklich nur Ger\u00fcchte. Unsere Nachforschungen ergaben ein ganz anderes Bild. In den Nachkriegsjahren steckte der Hamburger Fischmarkt in einer Krise. Es begab sich im Jahre 1951, dass durch einen dummen Zufall &hellip; <a href=\"https:\/\/www.palandun.de\/index.php\/2009\/10\/31\/wie-so-eine-zeitung-entsteht\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201eWie so eine Zeitung entsteht\u201c <\/span>weiterlesen<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-395","post","type-post","status-publish","format-standard","hentry","category-satire"],"_links":{"self":[{"href":"https:\/\/www.palandun.de\/index.php\/wp-json\/wp\/v2\/posts\/395","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.palandun.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.palandun.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.palandun.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.palandun.de\/index.php\/wp-json\/wp\/v2\/comments?post=395"}],"version-history":[{"count":1,"href":"https:\/\/www.palandun.de\/index.php\/wp-json\/wp\/v2\/posts\/395\/revisions"}],"predecessor-version":[{"id":396,"href":"https:\/\/www.palandun.de\/index.php\/wp-json\/wp\/v2\/posts\/395\/revisions\/396"}],"wp:attachment":[{"href":"https:\/\/www.palandun.de\/index.php\/wp-json\/wp\/v2\/media?parent=395"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.palandun.de\/index.php\/wp-json\/wp\/v2\/categories?post=395"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.palandun.de\/index.php\/wp-json\/wp\/v2\/tags?post=395"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}