{"id":463,"date":"2011-09-08T08:33:33","date_gmt":"2011-09-08T08:33:33","guid":{"rendered":"https:\/\/www.palandun.de\/?p=463"},"modified":"2020-02-29T08:34:00","modified_gmt":"2020-02-29T08:34:00","slug":"teuro-oder-was","status":"publish","type":"post","link":"https:\/\/www.palandun.de\/index.php\/2011\/09\/08\/teuro-oder-was\/","title":{"rendered":"Teuro oder was"},"content":{"rendered":"\n<p>\nEin Leitartikel in der Times fordert dazu auf, Deutschland aus der \nEuro-Zone rauszuwerfen, weil Deutschland nicht mehr unbegrenzt die \nKrisenl\u00e4nder st\u00fctzen will. Anders gesagt: ein Engl\u00e4nder, jemand, der \nnoch nicht mal richtig dabei ist und in einem Krisenland lebt, dass es \nselbst noch nicht bemerkt hat, will Deutschland rausschmei\u00dfen,&nbsp; um eine \nsch\u00f6nere EU zu haben. How wonderful.<\/p>\n\n\n\n<p>Gingen wir davon aus, \nDeutschland w\u00fcrde gehen, was passiert als n\u00e4chstes? Ich w\u00fcrde 10 Euro \noder vielleicht dann wieder 20 DM darauf wetten, dass \u00d6sterreich, \nNiederland und 1, 2 andere gleich mitgehen. Im Endeffekt haben wir dann \nein Europa der Pleitestaaten und ein Europa der Rumkrebsenden. Und \nNorwegen.<\/p>\n\n\n\n<p>Mit dem Thema \u201eWie viel machen Hedgefonts, Credit \nDefault Swaps und \u00e4hnliches, was kein Mensch braucht\u201c besch\u00e4ftigt sich \ndie Times ungerne. Die Zeitungen geh\u00f6renn\u00e4mlich&nbsp; den Leuten, die bei \nsolchen Spielereien verdienen. Anders gesagt: wir leben mittlerweile in \neiner Diktatur der Meinungsmachenden Million\u00e4re. Berlusconi ist nur der \neinzige, der das auch nach au\u00dfen zeigt. Alle anderen bleiben im \nVerborgenen, aber an den Hebeln der Macht. Ungew\u00e4hlt. Meistens auch \nunbemerkt.<\/p>\n\n\n\n<p>Nebenbei wird immer behauptet, Deutschland w\u00fcrde von \nder EU wirtschaftlich stark profitieren. Statistisch bewiesen. Wenn man \naber den Handels\u00fcberschuss Deutschlands innerhalb der EU gegenrechnet zu\n dem, was Deutschland an die EU zahlt, bleibt da nicht mehr viel \u00fcbrig\u2026<\/p>\n\n\n\n<p>Apropos\n Profiteur: die Rolle Frankreichs als uneigenn\u00fctziger Samariter des \nlybischen Volkes zahlt sich aus. Die ehemaligen Rebellen sichern Sarkozy\n ein Drittel der Erd\u00f6lproduktion zu. Westerwelle und&nbsp; Merkel, \naufgemerkt: so macht man das. Erst den Gewinn festschreiben, dann \neinmarschieren.<\/p>\n\n\n\n<p>Noch erfolgreicher war die FDP bei mir. Im \nInternet gibt es den Wahlomat. Man kann da im Internet alle Parteien vor\n einer Bundestags- oder Landtagswahl vergleichen und sogar eine \nReihenfolge aufstellen. Und die FDP hat jetzt dreimal hintereinander die\n Spitzenposition errungen: als unw\u00e4hlbarste Partei. Laut der Auswertung \nw\u00fcrde ich sogar eher NPD w\u00e4hlen als FDP. Das ist eine wirkliche \nLeistung. Bitte keine Panik: die Wahrscheinlichkeit, dass ich NPD w\u00e4hle,\n liegt auf gleicher H\u00f6he mit der Wahrscheinlichkeit, dass ein deutsches \nAtomkraftwerk GAUt. Jetzt wirklich keine Panik: sie liegt dadrunter.<\/p>\n\n\n\n<p>Ein\n Imker hat geklagt und gewonnen, weil seine Bienen Diebe sind. Die haben\n auf genmanipulierten Mais zur\u00fcckgegriffen. Was sie gar nicht durften. \nEr war dagegen und vernichtete seine Vorr\u00e4te. Weil genmanipulierter Mais\n nichts im Essen zu suchen hat sondern nur als Futtermittel zu benutzen \nist. So eine Kuh ist halt ein guter Filter, da kommt die Manipulation \ngar nicht beim Menschen an.<\/p>\n\n\n\n<p>&nbsp;Die EU-Kommission h\u00e4lt das Vorgehen \nder Bienen nicht f\u00fcr problematisch. Der Honig sei ungef\u00e4hrlich, weil die\n Bienen ihn aus Versehen gesammelt h\u00e4tten. Genau. Und morgen vermeldet \ndie EU-Kommission: Sie k\u00f6nnen ohne Probleme das Atomkraftwerk in \nFukushima besuchen. Das ist unproblematisch. Die Strahlung wurde \nversehentlich freigesetzt.<\/p>\n\n\n\n<p>Die Genmanipulatoren von Monsanto sind\n \u00fcbrigens genial: die haben einen kanadischen Bauern mal verklagt, weil \nihr Mais sein Feld verunreinigt hat und er damit ihre Patente verletzt \nhatte. Hiermit fordere ich den Chaos Computer Club auf, patentgesch\u00fctzte\n Software in die Systeme von Monsanto einzuschmuggeln und den \nPatentinhabern einen Tipp zu geben.<\/p>\n\n\n\n<p>Zum Schluss noch etwas \nProvinzposse. Man nehme einen B\u00fcrgermeister, eine Discounter-Kette und \nein billiges Grundst\u00fcck. Und das ganze lief wahrscheinlich so:<br>\u201eUnd wenn ihr auf dem Grundst\u00fcck au\u00dferhalb baut, dann bleiben aber die beiden anderen M\u00e4rkte erhalten?\u201c<br>\u201eKlar. Nat\u00fcrlich. Wir planen in naher Zukunft nicht, einen der L\u00e4den zu schlie\u00dfen.\u201c<br>\u201eDann ist ja gut.\u201c<\/p>\n\n\n\n<p>Und wenn der Bau beginnt, kommt dann pl\u00f6tzlich die Meldung, das doch einen Filiale geschlossen wird.<\/p>\n\n\n\n<p>B\u00fcrgermeister dazu: \u201eIch bin \u00fcberrascht.\u201c<br>Discounter: \u201eJa, also nahe Zukunft, das war doch gestern.\u201c<\/p>\n\n\n\n<p>Das\n ist \u00fcbrigens der gleiche B\u00fcrgermeister, der behauptet, niemand w\u00fcrde \neine neue S\u00fcdumgehung als Anschluss an die B486 als M\u00f6glichkeit nehmen, \ndie A3 zu umfahren.<\/p>\n\n\n\n<p>Und es wollte auch nie jemand eine Mauer bauen\u2026<\/p>\n\n\n\n<p>Wir\n hatten dieses Jahr \u00fcbrigens zwei Starkregenvorkommen in der Innenstadt,\n die jeweils nur in Abst\u00e4nden von Jahrzehnten vorkommen. Stimmt auch, \ndie letzten fanden 2009 statt, also im letzten Jahrzehnt.<\/p>\n\n\n\n<p>Aber \ndas Wetter spielt sowieso verr\u00fcckt. Ich bin von zuhause aus nach \nFrankfurt geradelt. Wettervorhersage: sonnig, hin und wieder leichte \nSchauer. Der leichte Schauer hielt 50 Minuten. So ein Bindfadenschauer. \nIch frage mich: was sind schwere Schauer? Ein Tag lang Dauerregen?<\/p>\n\n\n\n<p>In Holland hat einer die Arche nachgebaut. Ger\u00fcchteweise als Museumsschiff. Oder wei\u00df der mehr?<\/p>\n\n\n\n<p>Noch\n mehr Wahnsinn: bei der Bertha von Suttner-Schule darf die deutsche \nBundeswehr f\u00fcr ihre attraktiven Karrierechancen werben \u2013 vielleicht \ndemn\u00e4chst auch mal Vorbereitung zur \u00d6lforderung oder so was. Da ist \nnichts gegen auszusetzen. Bertha von Suttner war zwar \nFriedensnobelpreistr\u00e4gerin.&nbsp; Das waren aber Kriegstreiber wie Kissinger,\n Obama und Arafat auch. Eingestanden: zu Suttners Zeiten nahm man das \nnoch halbwegs ernst.&nbsp; Aber heute? Hauptsache die Schule hat einen Namen.\n Da muss nix hinter stehen.<\/p>\n\n\n\n<p>Und ganz zum Schluss: Der kleine \nGuido kann aus dem Koalitionsparadies abgeholt werden. Man spricht \n\u00fcbrigens von Guidolationshaft, wenn man mitten unter den Koalition\u00e4ren \nganz einsam ist.<br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ein Leitartikel in der Times fordert dazu auf, Deutschland aus der Euro-Zone rauszuwerfen, weil Deutschland nicht mehr unbegrenzt die Krisenl\u00e4nder st\u00fctzen will. Anders gesagt: ein Engl\u00e4nder, jemand, der noch nicht mal richtig dabei ist und in einem Krisenland lebt, dass es selbst noch nicht bemerkt hat, will Deutschland rausschmei\u00dfen,&nbsp; um eine sch\u00f6nere EU zu haben. &hellip; <a href=\"https:\/\/www.palandun.de\/index.php\/2011\/09\/08\/teuro-oder-was\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201eTeuro oder was\u201c <\/span>weiterlesen<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-463","post","type-post","status-publish","format-standard","hentry","category-satire"],"_links":{"self":[{"href":"https:\/\/www.palandun.de\/index.php\/wp-json\/wp\/v2\/posts\/463","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.palandun.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.palandun.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.palandun.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.palandun.de\/index.php\/wp-json\/wp\/v2\/comments?post=463"}],"version-history":[{"count":1,"href":"https:\/\/www.palandun.de\/index.php\/wp-json\/wp\/v2\/posts\/463\/revisions"}],"predecessor-version":[{"id":464,"href":"https:\/\/www.palandun.de\/index.php\/wp-json\/wp\/v2\/posts\/463\/revisions\/464"}],"wp:attachment":[{"href":"https:\/\/www.palandun.de\/index.php\/wp-json\/wp\/v2\/media?parent=463"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.palandun.de\/index.php\/wp-json\/wp\/v2\/categories?post=463"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.palandun.de\/index.php\/wp-json\/wp\/v2\/tags?post=463"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}